{"id":1753,"date":"2019-08-07T19:26:37","date_gmt":"2019-08-08T00:26:37","guid":{"rendered":"https:\/\/www.conape.org\/tvconape\/?p=1753"},"modified":"2019-09-14T19:28:48","modified_gmt":"2019-09-15T00:28:48","slug":"radioconape-en-vivo-programa-del-7-de-agosto-de-2019","status":"publish","type":"post","link":"https:\/\/www.conape.org\/tvconape\/radioconape-en-vivo-programa-del-7-de-agosto-de-2019\/","title":{"rendered":"#RadioCONAPE en vivo &#8211; Programa del 7 de Agosto de 2019"},"content":{"rendered":"<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2FperiodistasCONAPE%2Fvideos%2F387188355270482%2F&amp;show_text=0&amp;width=560\" width=\"560\" height=\"315\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>* Invitaci\u00f3n a la 4ta Cumbre Internacional de Periodismo &#8211;&nbsp;<a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/conapeper%C3%BA2019?source=feed_text&amp;epa=HASHTAG\" data-ft=\"{&quot;type&quot;:104,&quot;tn&quot;:&quot;*N&quot;}\"><span class=\"_5afx\"><span class=\"_58cl _5afz\" aria-label=\"hashtag\">#<\/span><span class=\"_58cm\">CONAPEPer\u00fa2019<\/span><\/span><\/a>&nbsp;en Lima, Per\u00fa.<\/p>\n<p>* Ciudadanos acusan a polic\u00edas de rateros, los cuales furon retirados de su cargo en Toluca, Estado de M\u00e9xico<\/p>\n<p>* Se suman m\u00e1s l\u00edderes sociales en contra de las acciones del Presidente Municipal de Almoloya de Ju\u00e1rez, Luis Maya Doro.<\/p>\n<p>* Reportaje especial del Museo de la Radio (MURADI) en Guadalajara, Jalisco (primera parte).<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/qvpncXKeS1s\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>* Invitaci\u00f3n a la 4ta Cumbre Internacional de Periodismo &#8211;&nbsp;#CONAPEPer\u00fa2019&nbsp;en Lima, Per\u00fa. * Ciudadanos acusan a polic\u00edas de rateros, los cuales furon retirados de su cargo en Toluca, Estado de M\u00e9xico * Se suman m\u00e1s l\u00edderes sociales en contra de las acciones del Presidente Municipal de Almoloya de Ju\u00e1rez, Luis Maya Doro. * Reportaje especial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[16],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.conape.org\/tvconape\/wp-content\/uploads\/2019\/09\/radioconape-en-vivo-programa-del-4.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6jC0G-sh","jetpack-related-posts":[{"id":1702,"url":"https:\/\/www.conape.org\/tvconape\/radioconape-en-vivo-programa-del-29-de-mayo-de-2019\/","url_meta":{"origin":1753,"position":0},"title":"#RadioCONAPE en vivo &#8211; Programa del 29 de Mayo de 2019","author":"TV CONAPE","date":"29 mayo, 2019","format":false,"excerpt":"\ufeff \u00a0 RadioCONAPE en vivo - Programa del 29 de Mayo de 2019","rel":"","context":"En &quot;#RadioCONAPE&quot;","block_context":{"text":"#RadioCONAPE","link":"https:\/\/www.conape.org\/tvconape\/category\/radioconape\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1705,"url":"https:\/\/www.conape.org\/tvconape\/radioconape-en-vivo-programa-del-3-de-junio-de-2019\/","url_meta":{"origin":1753,"position":1},"title":"#RadioCONAPE en vivo &#8211; Programa del 3 de Junio de 2019","author":"TV CONAPE","date":"3 junio, 2019","format":false,"excerpt":"#RadioCONAPE en vivo - Programa del 3 de Junio de 2019","rel":"","context":"En &quot;#RadioCONAPE&quot;","block_context":{"text":"#RadioCONAPE","link":"https:\/\/www.conape.org\/tvconape\/category\/radioconape\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1708,"url":"https:\/\/www.conape.org\/tvconape\/radioconape-en-vivo-programa-del-5-de-junio-de-2019\/","url_meta":{"origin":1753,"position":2},"title":"#RadioCONAPE en vivo &#8211; Programa del 5 de Junio de 2019","author":"TV CONAPE","date":"5 junio, 2019","format":false,"excerpt":"RadioCONAPE en vivo - Programa del 5 de Junio de 2019 \u00a0","rel":"","context":"En &quot;#RadioCONAPE&quot;","block_context":{"text":"#RadioCONAPE","link":"https:\/\/www.conape.org\/tvconape\/category\/radioconape\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1711,"url":"https:\/\/www.conape.org\/tvconape\/radioconape-en-vivo-programa-del-10-de-junio-de-2019\/","url_meta":{"origin":1753,"position":3},"title":"#RadioCONAPE en vivo &#8211; Programa del 10 de Junio de 2019","author":"TV CONAPE","date":"10 junio, 2019","format":false,"excerpt":"\u00a0 RadioCONAPE en vivo - Programa del 10 de Junio de 2019 \u00a0","rel":"","context":"En &quot;#RadioCONAPE&quot;","block_context":{"text":"#RadioCONAPE","link":"https:\/\/www.conape.org\/tvconape\/category\/radioconape\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.conape.org\/tvconape\/wp-content\/uploads\/2019\/06\/radioconape-en-vivo-programa-del-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.conape.org\/tvconape\/wp-content\/uploads\/2019\/06\/radioconape-en-vivo-programa-del-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.conape.org\/tvconape\/wp-content\/uploads\/2019\/06\/radioconape-en-vivo-programa-del-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.conape.org\/tvconape\/wp-content\/uploads\/2019\/06\/radioconape-en-vivo-programa-del-3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.conape.org\/tvconape\/wp-content\/uploads\/2019\/06\/radioconape-en-vivo-programa-del-3.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1714,"url":"https:\/\/www.conape.org\/tvconape\/radioconape-en-vivo-programa-del-17-de-junio-de-2019\/","url_meta":{"origin":1753,"position":4},"title":"#RadioCONAPE en vivo &#8211; Programa del 17 de Junio de 2019","author":"TV CONAPE","date":"17 junio, 2019","format":false,"excerpt":"#RadioCONAPE\u00a0en vivo - Programa del 17 de Junio de 2019 \u00a0","rel":"","context":"En &quot;#RadioCONAPE&quot;","block_context":{"text":"#RadioCONAPE","link":"https:\/\/www.conape.org\/tvconape\/category\/radioconape\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1718,"url":"https:\/\/www.conape.org\/tvconape\/radioconape-en-vivo-programa-del-24-de-junio-de-2019\/","url_meta":{"origin":1753,"position":5},"title":"#RadioCONAPE en vivo &#8211; Programa del 24 de Junio de 2019","author":"TV CONAPE","date":"25 junio, 2019","format":false,"excerpt":"\u00a0 #RadioCONAPE en vivo - Programa del 24 de Junio de 2019 \u00a0","rel":"","context":"En &quot;#RadioCONAPE&quot;","block_context":{"text":"#RadioCONAPE","link":"https:\/\/www.conape.org\/tvconape\/category\/radioconape\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/posts\/1753"}],"collection":[{"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/comments?post=1753"}],"version-history":[{"count":2,"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/posts\/1753\/revisions"}],"predecessor-version":[{"id":1756,"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/posts\/1753\/revisions\/1756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/media\/1755"}],"wp:attachment":[{"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/media?parent=1753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/categories?post=1753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conape.org\/tvconape\/wp-json\/wp\/v2\/tags?post=1753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}